{"id":32986,"date":"2026-07-15T16:09:30","date_gmt":"2026-07-15T14:09:30","guid":{"rendered":"https:\/\/www.amcon-eu.com\/impressum\/"},"modified":"2026-07-15T16:17:24","modified_gmt":"2026-07-15T14:17:24","slug":"impressum","status":"publish","type":"page","link":"https:\/\/www.amcon-eu.com\/de\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]<\/p>\r\n\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document impressum cmplz-document-all\"><p><i>Dieses Impressum wurde zuletzt am Juli 15, 2026 aktualisiert.<\/i><\/p><p class=\"cmplz-subtitle\">Der Eigent\u00fcmer dieser Website ist:<\/p><p>AMCON Europe s.r.o. Spole\u010dnost s ru\u010den\u00edm omezen\u00fdm (s.r.o.)<br>Za Trati 207, 252 19 Chrastany, Praha-zapad, Czech Republic<br>Tschechische Republik<br>E-Mail:&nbsp;a&#109;&#099;one&#117;&#114;&#111;pe&#064;amc&#111;&#110;&#045;e&#117;.&#099;&#111;&#109;<br>Telefonnummer: +420 211 150 120<br>USt-IdNr:&nbsp;CZ24831115<\/p><p class=\"cmplz-subtitle\">Der\/die gesetzliche(n) Vertreter von AMCON Europe s.r.o. Spole\u010dnost s ru\u010den\u00edm omezen\u00fdm (s.r.o.):<\/p><p>Robbert Adrianus Pieter van Leeuwen, Shoichi Sasaki<\/p><h2>1. Allgemein<\/h2><p class=\"cmplz-subtitle\">1.1 Wir sind bei Municipal Court in Prague unter der Lizenz- oder Registrierungsnummer registriert:<\/p><p>C 178375<\/p><p>Wir sind nicht bereit oder verpflichtet, an Streitbeilegungsverfahren vor einer Verbraucherschlichtungsstelle teilzunehmen.<\/p><h2>2. Die folgenden Angaben sind nach deutscher Gesetzgebung zwingend erforderlich.<\/h2><p class=\"cmplz-subtitle\">2.1 Die Eigentumsanteile der Gesellschaft (Aktienkapital), die von ihr ausgegeben wurden:<\/p><p>12 080 000 CZK<\/p><\/div><p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\r\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] [\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-tmp.php","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-32986","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Impressum | AMCON Europe<\/title>\n<meta name=\"description\" content=\"Offizielles Impressum der AMCON Europe s.r.o. Hier finden Sie alle rechtlichen Hinweise, Kontaktdaten und Unternehmensinformationen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.amcon-eu.com\/de\/impressum\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impressum | AMCON Europe\" \/>\n<meta property=\"og:description\" content=\"Offizielles Impressum der AMCON Europe s.r.o. Hier finden Sie alle rechtlichen Hinweise, Kontaktdaten und Unternehmensinformationen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.amcon-eu.com\/de\/impressum\/\" \/>\n<meta property=\"og:site_name\" content=\"AMCON Europe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/AMCON.Europe.sro\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T14:17:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.amcon-eu.com\/wp-content\/uploads\/2025\/06\/AMCON-Europe_site-image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.amcon-eu.com\/de\/impressum\/\",\"url\":\"https:\/\/www.amcon-eu.com\/de\/impressum\/\",\"name\":\"Impressum | AMCON Europe\",\"isPartOf\":{\"@id\":\"https:\/\/www.amcon-eu.com\/de\/#website\"},\"datePublished\":\"2026-07-15T14:09:30+00:00\",\"dateModified\":\"2026-07-15T14:17:24+00:00\",\"description\":\"Offizielles Impressum der AMCON Europe s.r.o. Hier finden Sie alle rechtlichen Hinweise, Kontaktdaten und Unternehmensinformationen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.amcon-eu.com\/de\/impressum\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.amcon-eu.com\/de\/impressum\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.amcon-eu.com\/de\/impressum\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u30db\u30fc\u30e0\",\"item\":\"https:\/\/www.amcon-eu.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impressum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.amcon-eu.com\/de\/#website\",\"url\":\"https:\/\/www.amcon-eu.com\/de\/\",\"name\":\"AMCON Europe\",\"description\":\"Bequeme Schlammentw\u00e4sserung\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.amcon-eu.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impressum | AMCON Europe","description":"Offizielles Impressum der AMCON Europe s.r.o. Hier finden Sie alle rechtlichen Hinweise, Kontaktdaten und Unternehmensinformationen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.amcon-eu.com\/de\/impressum\/","og_locale":"de_DE","og_type":"article","og_title":"Impressum | AMCON Europe","og_description":"Offizielles Impressum der AMCON Europe s.r.o. Hier finden Sie alle rechtlichen Hinweise, Kontaktdaten und Unternehmensinformationen.","og_url":"https:\/\/www.amcon-eu.com\/de\/impressum\/","og_site_name":"AMCON Europe","article_publisher":"https:\/\/www.facebook.com\/AMCON.Europe.sro","article_modified_time":"2026-07-15T14:17:24+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.amcon-eu.com\/wp-content\/uploads\/2025\/06\/AMCON-Europe_site-image.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.amcon-eu.com\/de\/impressum\/","url":"https:\/\/www.amcon-eu.com\/de\/impressum\/","name":"Impressum | AMCON Europe","isPartOf":{"@id":"https:\/\/www.amcon-eu.com\/de\/#website"},"datePublished":"2026-07-15T14:09:30+00:00","dateModified":"2026-07-15T14:17:24+00:00","description":"Offizielles Impressum der AMCON Europe s.r.o. Hier finden Sie alle rechtlichen Hinweise, Kontaktdaten und Unternehmensinformationen.","breadcrumb":{"@id":"https:\/\/www.amcon-eu.com\/de\/impressum\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.amcon-eu.com\/de\/impressum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.amcon-eu.com\/de\/impressum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u30db\u30fc\u30e0","item":"https:\/\/www.amcon-eu.com\/de\/"},{"@type":"ListItem","position":2,"name":"Impressum"}]},{"@type":"WebSite","@id":"https:\/\/www.amcon-eu.com\/de\/#website","url":"https:\/\/www.amcon-eu.com\/de\/","name":"AMCON Europe","description":"Bequeme Schlammentw\u00e4sserung","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.amcon-eu.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.amcon-eu.com\/de\/wp-json\/wp\/v2\/pages\/32986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.amcon-eu.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.amcon-eu.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.amcon-eu.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.amcon-eu.com\/de\/wp-json\/wp\/v2\/comments?post=32986"}],"version-history":[{"count":1,"href":"https:\/\/www.amcon-eu.com\/de\/wp-json\/wp\/v2\/pages\/32986\/revisions"}],"predecessor-version":[{"id":32987,"href":"https:\/\/www.amcon-eu.com\/de\/wp-json\/wp\/v2\/pages\/32986\/revisions\/32987"}],"wp:attachment":[{"href":"https:\/\/www.amcon-eu.com\/de\/wp-json\/wp\/v2\/media?parent=32986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}